{"id":801,"date":"2019-03-25T20:09:00","date_gmt":"2019-03-26T01:09:00","guid":{"rendered":"https:\/\/efficiencymb.ca\/whats-the-difference-between-energuide-and-energy-star\/"},"modified":"2023-06-21T12:05:29","modified_gmt":"2023-06-21T17:05:29","slug":"whats-the-difference-between-energuide-and-energy-star","status":"publish","type":"post","link":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/","title":{"rendered":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous recommandons de choisir des appareils certifi\u00e9s ENERGY STAR; ils se rangent parmi les 10 \u00e0 30 % d\u2019appareils les plus \u00e9co\u00e9nerg\u00e9tiques de leur classe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les appareils vendus au Canada portent une \u00e9tiquette \u00c9nerGuide, mais ils ne sont pas tous certifi\u00e9s ENERGY STAR. En bref, deux \u00e9tiquettes valent mieux qu\u2019une!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/efficiencymb.ca\/assets\/images\/headshots\/ask-kelsey.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kelsey<br>Sp\u00e9cialiste des appareils m\u00e9nagers et \u00e9lectroniques<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">AVEZ-VOUS UNE QUESTION \u00c0 POSER \u00c0 NOTRE \u00c9QUIPE DE SP\u00c9CIALISTES DE L&rsquo;\u00c9NERGIE?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:EnergyTeam@efficiencymb.ca\">Envoyez-nous un courriel<\/a>. Votre question peut faire l\u2019objet d\u2019une future publication.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires.<\/p>\n","protected":false},"author":10,"featured_media":802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[40],"tags":[5,15,3,7],"class_list":["post-801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ask-our-energy-team","tag-home","tag-appliances","tag-efficiency-tips","tag-energy-star"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba<\/title>\n<meta name=\"description\" content=\"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba\" \/>\n<meta property=\"og:description\" content=\"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/\" \/>\n<meta property=\"og:site_name\" content=\"Efficiency Manitoba\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-26T01:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T17:05:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alyssa Heuchert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alyssa Heuchert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/\"},\"author\":{\"name\":\"Alyssa Heuchert\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/person\\\/3cec4c5f343480c23b62eb570c36d947\"},\"headline\":\"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30?\",\"datePublished\":\"2019-03-26T01:09:00+00:00\",\"dateModified\":\"2023-06-21T17:05:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/\"},\"wordCount\":182,\"publisher\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg\",\"keywords\":[\"HOME\",\"APPLIANCES\",\"EFFICIENCY TIPS\",\"ENERGY STAR\u00ae\"],\"articleSection\":[\"ASK OUR ENERGY TEAM\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/\",\"name\":\"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg\",\"datePublished\":\"2019-03-26T01:09:00+00:00\",\"dateModified\":\"2023-06-21T17:05:29+00:00\",\"description\":\"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#primaryimage\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg\",\"width\":2400,\"height\":1350,\"caption\":\"Logos \u00c9nerGuide et Energy Stars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/articles\\\/whats-the-difference-between-energuide-and-energy-star\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"name\":\"Efficiency Manitoba\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/efficiencymb.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\",\"name\":\"Efficiency Manitoba\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"width\":388,\"height\":91,\"caption\":\"Efficiency Manitoba\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.\",\"legalName\":\"Efficiency Manitoba\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/person\\\/3cec4c5f343480c23b62eb570c36d947\",\"name\":\"Alyssa Heuchert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g\",\"caption\":\"Alyssa Heuchert\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba","description":"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba","og_description":"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.","og_url":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/","og_site_name":"Efficiency Manitoba","article_published_time":"2019-03-26T01:09:00+00:00","article_modified_time":"2023-06-21T17:05:29+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg","type":"image\/jpeg"}],"author":"Alyssa Heuchert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alyssa Heuchert","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#article","isPartOf":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/"},"author":{"name":"Alyssa Heuchert","@id":"https:\/\/efficiencymb.ca\/#\/schema\/person\/3cec4c5f343480c23b62eb570c36d947"},"headline":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30?","datePublished":"2019-03-26T01:09:00+00:00","dateModified":"2023-06-21T17:05:29+00:00","mainEntityOfPage":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/"},"wordCount":182,"publisher":{"@id":"https:\/\/efficiencymb.ca\/#organization"},"image":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#primaryimage"},"thumbnailUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg","keywords":["HOME","APPLIANCES","EFFICIENCY TIPS","ENERGY STAR\u00ae"],"articleSection":["ASK OUR ENERGY TEAM"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/","url":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/","name":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30? &#8212; Efficiency Manitoba","isPartOf":{"@id":"https:\/\/efficiencymb.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#primaryimage"},"image":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#primaryimage"},"thumbnailUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg","datePublished":"2019-03-26T01:09:00+00:00","dateModified":"2023-06-21T17:05:29+00:00","description":"Bien que les \u00e9tiquettes \u00c9nerGuide et ENERGY STAR vous donnent toutes les deux de pr\u00e9cieux renseignements sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique d\u2019un appareil, elles indiquent des choses tr\u00e8s diff\u00e9rentes. L\u2019\u00e9tiquette \u00c9nerGuide indique combien d\u2019\u00e9lectricit\u00e9 consomme un appareil au cours d\u2019une ann\u00e9e et compare le rendement de ce dernier avec celui de produits similaires. ENERGY STAR est un programme de renomm\u00e9e internationale dont le symbole est appos\u00e9 sur les produits les plus \u00e9co\u00e9nerg\u00e9tiques sur le march\u00e9.","breadcrumb":{"@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#primaryimage","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/2020\/03\/banner-blog-ask-our-energy-team-energuide-vs-energy-star_2x.jpg","width":2400,"height":1350,"caption":"Logos \u00c9nerGuide et Energy Stars"},{"@type":"BreadcrumbList","@id":"https:\/\/efficiencymb.ca\/fr\/articles\/whats-the-difference-between-energuide-and-energy-star\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/efficiencymb.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Quelle est la diff\u00e9rence entre \u00c9nerGuide et ENERGY STAR\u1d39\u1d30?"}]},{"@type":"WebSite","@id":"https:\/\/efficiencymb.ca\/#website","url":"https:\/\/efficiencymb.ca\/","name":"Efficiency Manitoba","description":"","publisher":{"@id":"https:\/\/efficiencymb.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efficiencymb.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/efficiencymb.ca\/#organization","name":"Efficiency Manitoba","url":"https:\/\/efficiencymb.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","width":388,"height":91,"caption":"Efficiency Manitoba"},"image":{"@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/"},"description":"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.","legalName":"Efficiency Manitoba"},{"@type":"Person","@id":"https:\/\/efficiencymb.ca\/#\/schema\/person\/3cec4c5f343480c23b62eb570c36d947","name":"Alyssa Heuchert","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1dc5063ecb17cbb29acb851072e9c6e4b103c251e84ec712cd375935f7519e3?s=96&d=mm&r=g","caption":"Alyssa Heuchert"}}]}},"_links":{"self":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/posts\/801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/comments?post=801"}],"version-history":[{"count":6,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/posts\/801\/revisions"}],"predecessor-version":[{"id":27702,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/posts\/801\/revisions\/27702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/media\/802"}],"wp:attachment":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/media?parent=801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/categories?post=801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/tags?post=801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}