{"id":90956,"date":"2026-08-06T08:09:11","date_gmt":"2026-08-06T13:09:11","guid":{"rendered":"https:\/\/efficiencymb.ca\/?page_id=90956"},"modified":"2026-08-06T08:09:12","modified_gmt":"2026-08-06T13:09:12","slug":"prime-etancheisation-air-foire-aux-questions","status":"publish","type":"page","link":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/","title":{"rendered":"Foire aux questions remise prime d&rsquo;\u00e9tanch\u00e9isation \u00c0 l&rsquo;air"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-content-columns\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-center is-style-hero-heading\">FOIRE AUX QUESTIONS<\/h1>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center is-style-hero-heading-grey\">PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Voici certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>RENSEIGNEMENTS DE BASE<\/strong><\/h4>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Qu\u2019est-ce que la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui peut s\u2019ajouter \u00e0 la remise pour l\u2019isolation des maisons?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">La prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air est un incitatif con\u00e7u pour encourager les participants au programme de remises pour l\u2019isolation des maisons \u00e0 effectuer une \u00e9tanch\u00e9isation \u00e0 l\u2019air compl\u00e8te dans le cadre de leurs projets d\u2019isolation. Pour recevoir la prime, les participants doivent effectuer une \u00e9valuation \u00c9nerGuide avant et apr\u00e8s les r\u00e9novations afin de quantifier l\u2019am\u00e9lioration du taux de fuite d\u2019air de leur maison. La valeur en dollars de la prime est fond\u00e9e sur le pourcentage d\u2019am\u00e9lioration.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Comment indiquer que j\u2019aimerais recevoir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air avec la remise pour l\u2019isolation des maisons?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Dans le formulaire de demande de la remise pour l\u2019isolation des maisons, une question vous demandera si vous d\u00e9sirez recevoir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. \u00c0 la fin de votre projet d\u2019isolation et d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air, vous devrez soumettre des copies de vos rapports d\u2019\u00e9valuation avant et apr\u00e8s les r\u00e9novations, particuli\u00e8rement vos fiches d\u2019information \u00e0 l\u2019intention des propri\u00e9taires, afin d\u2019indiquer vos taux de fuite d\u2019air avant et apr\u00e8s les r\u00e9novations.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Quels sont les avantages d\u2019\u00e9tanch\u00e9iser ma maison?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">L\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air comporte plusieurs avantages, notamment les suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-small\">\n<li>une r\u00e9duction de la consommation d\u2019\u00e9nergie et des factures \u00e9nerg\u00e9tiques;<\/li>\n\n\n\n<li>une am\u00e9lioration de la qualit\u00e9 de l\u2019air int\u00e9rieur, du confort et de l\u2019insonorisation;<\/li>\n\n\n\n<li>une r\u00e9duction du risque d\u2019accumulation d\u2019humidit\u00e9 et de probl\u00e8mes connexes;<\/li>\n\n\n\n<li>une prolongation de la dur\u00e9e de vie des syst\u00e8mes de chauffage et de ventilation.<\/li>\n<\/ul>\n<\/details>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>ADMISSIBILIT\u00c9 ET EXIGENCES<\/strong><\/h4>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Mon projet d\u2019isolation et d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air doit-il \u00eatre effectu\u00e9 par un entrepreneur pour \u00eatre admissible \u00e0 la remise pour l\u2019isolation des maisons et \u00e0 la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Non. Bien qu\u2019un entrepreneur inscrit ou un d\u00e9taillant doive pr\u00e9senter votre demande de remise pour l\u2019isolation des maisons, vous pouvez effectuer vous-m\u00eame les travaux ou les confier \u00e0 un entrepreneur.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Comment m\u2019assurer que le taux de fuite d\u2019air de ma maison est am\u00e9lior\u00e9 d\u2019au moins 10 %?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Les techniques d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air varient selon les besoins particuliers de votre maison et de l\u2019endroit o\u00f9 vous ajoutez l\u2019isolant. Pour vos r\u00e9novations, nous vous recommandons de faire appel \u00e0 un entrepreneur d\u2019exp\u00e9rience dans le domaine de l\u2019isolation, qui conna\u00eet les points de fuite courants. Vous pouvez \u00e9galement consulter les <a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#ressources\" target=\"_blank\" rel=\"noreferrer noopener\">ressources<\/a> \u00e9num\u00e9r\u00e9es sur notre page Web pour conna\u00eetre les pratiques exemplaires en mati\u00e8re d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous effectuez toutes les am\u00e9liorations admissibles en mati\u00e8re d\u2019isolation dans le cadre du m\u00eame projet de r\u00e9novations et que vous colmatez tous les points de fuite d\u2019air indiqu\u00e9s dans votre \u00e9valuation \u00c9nerGuide, vous pourrez plus facilement respecter la condition d\u2019am\u00e9lioration minimale de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous \u00e9tanch\u00e9isez votre maison \u00e0 l\u2019air, il est important de r\u00e9gler tout probl\u00e8me d\u2019humidit\u00e9 existant avant de commencer les travaux. En emprisonnant l\u2019humidit\u00e9 dans un endroit bien \u00e9tanch\u00e9is\u00e9, vous pouvez r\u00e9duire le potentiel de s\u00e9chage et aggraver le probl\u00e8me. Il est \u00e9galement important de savoir comment l\u2019isolation et l\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air peuvent modifier la fa\u00e7on dont l\u2019air circule vers l\u2019int\u00e9rieur et l\u2019ext\u00e9rieur de votre maison. Une ventilation ad\u00e9quate est essentielle pour assurer une bonne qualit\u00e9 de l\u2019air int\u00e9rieur, particuli\u00e8rement dans une maison herm\u00e9tique ou une maison vis\u00e9e par des mesures d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. Obtenez de plus amples renseignements sur les r\u00e9novations \u00e9co\u00e9nerg\u00e9tiques et la qualit\u00e9 de l\u2019air int\u00e9rieur.<\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Puis-je recevoir seulement la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air et non la remise pour l\u2019isolation des maisons?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Non. Une am\u00e9lioration de l\u2019isolation qui est admissible doit \u00eatre effectu\u00e9e dans le cadre de notre programme de remises pour l\u2019isolation des maisons afin qu\u2019une prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air puisse \u00eatre vers\u00e9e.<\/p>\n<\/details>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Puis-je obtenir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air plusieurs fois?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Oui. Vous pouvez demander plusieurs fois notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons. Si vous avez d\u00e9j\u00e0 re\u00e7u la prime, le taux de fuite d\u2019air indiqu\u00e9 dans votre \u00e9valuation apr\u00e8s les r\u00e9novations servira de r\u00e9f\u00e9rence pour votre nouveau projet. Suivez les \u00e9tapes pour participer, en ayant comme point de d\u00e9part l\u2019\u00e9tape 3 : Pr\u00e9sentez une demande de remise pour l\u2019isolation des maisons et de prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. Apr\u00e8s avoir re\u00e7u l\u2019approbation et achev\u00e9 votre projet d\u2019isolation et d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air, vous devrez vous soumettre \u00e0 une \u00e9valuation apr\u00e8s les r\u00e9novations, qui nous permettra de quantifier le changement dans votre taux de fuite d\u2019air.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez noter que, m\u00eame s\u2019il est possible de demander plusieurs fois notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air s\u2019ajoutant \u00e0 la remise pour l\u2019isolation des maisons, la r\u00e9alisation de divers projets de r\u00e9novations visant \u00e0 am\u00e9liorer l\u2019isolation et l\u2019\u00e9tanch\u00e9isation de l\u2019air pourrait faire en sorte qu\u2019il est plus difficile d\u2019atteindre l\u2019am\u00e9lioration minimale du taux de fuite d\u2019air exig\u00e9e pour recevoir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.<\/p>\n<\/details>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c9VALUATIONS \u00c9NERGUIDE<\/strong><\/h4>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Qui planifie les \u00e9valuations \u00c9nerGuide et paie pour celles-ci?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Le propri\u00e9taire est responsable de communiquer avec un <a href=\"https:\/\/efficiencymb.ca\/fr\/organismes-de-service-energuide\/\" target=\"_blank\" rel=\"noreferrer noopener\">organisme de service<\/a> pour planifier les \u00e9valuations avant et apr\u00e8s les r\u00e9novations et il doit payer directement l\u2019organisme de service. Les propri\u00e9taires peuvent \u00eatre admissibles \u00e0 une remise de 400 $ sur le co\u00fbt de l\u2019\u00e9valuation \u00c9nerGuide avant les r\u00e9novations dans le cadre de notre <a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-evaluation-energuide-maison\/\" target=\"_blank\" rel=\"noreferrer noopener\">remise pour une \u00e9valuation \u00c9nerGuide de votre maison<\/a>. Il incombe au propri\u00e9taire de soumettre sa demande \u00e0 Efficacit\u00e9 Manitoba dans les 90 jours suivant la date de l\u2019\u00e9valuation avant les r\u00e9novations. La remise pour l\u2019isolation des maisons est un processus de demande distinct.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous n\u2019offrons pas de remise sur le co\u00fbt d\u2019une \u00e9valuation apr\u00e8s les r\u00e9novations. La prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons en tient compte. Elle vous aidera \u00e0 assumer les co\u00fbts de l\u2019\u00e9tanch\u00e9isation de votre maison et de l\u2019\u00e9valuation \u00c9nerGuide apr\u00e8s les r\u00e9novations.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Comment l\u2019essai du moteur souffleur quantifie-t-il le changement du taux de renouvellement d\u2019air par heure (tr\/h)?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Lors d\u2019une \u00e9valuation \u00c9nerGuide de votre maison, un conseiller \u00e9nerg\u00e9tique ou un autre professionnel certifi\u00e9 quantifiera le taux de fuite d\u2019air en proc\u00e9dant \u00e0 la mise sous pression et \u00e0 la d\u00e9pressurisation de votre maison \u00e0 l\u2019aide d\u2019un grand ventilateur \u00e9talonn\u00e9 souvent appel\u00e9 un \u00ab moteur souffleur \u00bb. Le taux de fuite d\u2019air sera quantifi\u00e9 en renouvellement d\u2019air par heure (tr\/h) et figurera dans votre fiche d\u2019information \u00e0 l\u2019intention du propri\u00e9taire avec les possibilit\u00e9s d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. Un tr\/h de 5 ou plus indique que vous disposez de bonnes possibilit\u00e9s d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. Une \u00e9valuation apr\u00e8s les r\u00e9novations permettra d\u2019\u00e9valuer le changement apport\u00e9 \u00e0 votre taux de fuite d\u2019air.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>J\u2019ai d\u00e9j\u00e0 obtenu une \u00e9valuation \u00c9nerGuide. Dois-je en obtenir une autre pour recevoir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Si vous ne connaissiez pas l\u2019offre de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air avant d\u2019obtenir une \u00e9valuation \u00c9nerGuide, vous pouvez la demander si l\u2019\u00e9valuation a \u00e9t\u00e9 r\u00e9alis\u00e9e le 1<sup>er<\/sup> janvier 2025 ou apr\u00e8s. Si l\u2019\u00e9valuation a \u00e9t\u00e9 men\u00e9e avant cette date et que vous n\u2019avez pas encore apport\u00e9 les am\u00e9liorations \u00e0 votre maison, vous pourriez \u00eatre admissible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, si vous avez obtenu une \u00e9valuation \u00c9nerGuide apr\u00e8s les r\u00e9novations et qu\u2019aucune autre am\u00e9lioration n\u2019a depuis \u00e9t\u00e9 apport\u00e9e \u00e0 la maison, cette \u00e9valuation servira de r\u00e9f\u00e9rence avant les r\u00e9novations. Une nouvelle \u00e9valuation apr\u00e8s les r\u00e9novations sera exig\u00e9e \u00e0 la fin de votre projet d\u2019isolation afin de quantifier le nouveau changement du taux de fuite d\u2019air.<\/p>\n<\/details>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>PAIEMENTS ET AUTRES REMISES<\/strong><\/h4>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Comment recevoir la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air? Est-ce qu\u2019elle me sera vers\u00e9e directement ou sera-t-elle remise \u00e0 l\u2019entrepreneur ou au d\u00e9taillant?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">La prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air est ajout\u00e9e \u00e0 la remise pour un projet d\u2019isolation admissible offerte dans le cadre de notre programme de remises pour l\u2019isolation des maisons. Le ch\u00e8que de la remise sera envoy\u00e9 au propri\u00e9taire.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Qu\u2019est-ce qui distingue la remise pour l\u2019isolation des maisons et la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air de votre offre relative aux r\u00e9novations \u00e9co\u00e9nerg\u00e9tiques r\u00e9sidentielles?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Les deux offres exigent une \u00e9valuation \u00c9nerGuide avant et apr\u00e8s les r\u00e9novations. <a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/home-energy-retrofit-program\/\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019offre relative aux r\u00e9novations \u00e9co\u00e9nerg\u00e9tiques r\u00e9sidentielles<\/a> vise des r\u00e9novations qui touchent l\u2019ensemble de la maison et qui donneront lieu \u00e0 des \u00e9conomies d\u2019\u00e9nergie consid\u00e9rables. Il s\u2019agit d\u2019une meilleure option pour les consommateurs qui effectuent \u00e9galement d\u2019autres am\u00e9liorations, par exemple un changement de syst\u00e8me de chauffage et de refroidissement en plus de l\u2019ajout d\u2019isolant \u00e0 leur maison.<\/p>\n<\/details>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez des questions au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons? Obtenez ici des r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es. <\/p>\n","protected":false},"author":10,"featured_media":2601,"parent":13124,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-90956","page","type-page","status-publish","has-post-thumbnail","hentry","page_cat-programs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Foire aux questions remise prime d&#039;\u00e9tanch\u00e9isation \u00c0 l&#039;air &#8212; Efficiency Manitoba<\/title>\n<meta name=\"description\" content=\"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foire aux questions remise prime d&#039;\u00e9tanch\u00e9isation \u00c0 l&#039;air &#8212; Efficiency Manitoba\" \/>\n<meta property=\"og:description\" content=\"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/\" \/>\n<meta property=\"og:site_name\" content=\"Efficiency Manitoba\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T13:09:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/home-insulation-banner_v2_2x.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/\",\"name\":\"Foire aux questions remise prime d'\u00e9tanch\u00e9isation \u00c0 l'air &#8212; Efficiency Manitoba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/home-insulation-banner_v2_2x.jpg\",\"datePublished\":\"2026-08-06T13:09:11+00:00\",\"dateModified\":\"2026-08-06T13:09:12+00:00\",\"description\":\"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/home-insulation-banner_v2_2x.jpg\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/home-insulation-banner_v2_2x.jpg\",\"width\":2400,\"height\":1350,\"caption\":\"Isolation en fibre de verre d'un mur int\u00e9rieur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-etancheisation-air-foire-aux-questions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ma Maison\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remise pour l\u2019isolation des maisons\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Foire aux questions remise prime d&#8217;\u00e9tanch\u00e9isation \u00c0 l&#8217;air\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"name\":\"Efficiency Manitoba\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/efficiencymb.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\",\"name\":\"Efficiency Manitoba\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"width\":388,\"height\":91,\"caption\":\"Efficiency Manitoba\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.\",\"legalName\":\"Efficiency Manitoba\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foire aux questions remise prime d'\u00e9tanch\u00e9isation \u00c0 l'air &#8212; Efficiency Manitoba","description":"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/","og_locale":"fr_FR","og_type":"article","og_title":"Foire aux questions remise prime d'\u00e9tanch\u00e9isation \u00c0 l'air &#8212; Efficiency Manitoba","og_description":"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.","og_url":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/","og_site_name":"Efficiency Manitoba","article_modified_time":"2026-08-06T13:09:12+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/home-insulation-banner_v2_2x.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/","url":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/","name":"Foire aux questions remise prime d'\u00e9tanch\u00e9isation \u00c0 l'air &#8212; Efficiency Manitoba","isPartOf":{"@id":"https:\/\/efficiencymb.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/#primaryimage"},"image":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/#primaryimage"},"thumbnailUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/home-insulation-banner_v2_2x.jpg","datePublished":"2026-08-06T13:09:11+00:00","dateModified":"2026-08-06T13:09:12+00:00","description":"Voici les r\u00e9ponses \u00e0 certaines questions fr\u00e9quemment pos\u00e9es au sujet de la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air qui s\u2019ajoute \u00e0 la remise pour l\u2019isolation des maisons.","breadcrumb":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/#primaryimage","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/home-insulation-banner_v2_2x.jpg","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/home-insulation-banner_v2_2x.jpg","width":2400,"height":1350,"caption":"Isolation en fibre de verre d'un mur int\u00e9rieur"},{"@type":"BreadcrumbList","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/efficiencymb.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ma Maison","item":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/"},{"@type":"ListItem","position":3,"name":"Remise pour l\u2019isolation des maisons","item":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/"},{"@type":"ListItem","position":4,"name":"Foire aux questions remise prime d&#8217;\u00e9tanch\u00e9isation \u00c0 l&#8217;air"}]},{"@type":"WebSite","@id":"https:\/\/efficiencymb.ca\/#website","url":"https:\/\/efficiencymb.ca\/","name":"Efficiency Manitoba","description":"","publisher":{"@id":"https:\/\/efficiencymb.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efficiencymb.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/efficiencymb.ca\/#organization","name":"Efficiency Manitoba","url":"https:\/\/efficiencymb.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","width":388,"height":91,"caption":"Efficiency Manitoba"},"image":{"@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/"},"description":"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.","legalName":"Efficiency Manitoba"}]}},"_links":{"self":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/90956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/comments?post=90956"}],"version-history":[{"count":4,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/90956\/revisions"}],"predecessor-version":[{"id":91319,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/90956\/revisions\/91319"}],"up":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/13124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/media\/2601"}],"wp:attachment":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/media?parent=90956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}