{"id":89896,"date":"2026-08-05T08:00:00","date_gmt":"2026-08-05T13:00:00","guid":{"rendered":"https:\/\/efficiencymb.ca\/?page_id=89896"},"modified":"2026-08-25T15:19:20","modified_gmt":"2026-08-25T20:19:20","slug":"prime-detancheisation-a-lair","status":"publish","type":"page","link":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/","title":{"rendered":"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-content-wide\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-hero-heading-grey\">TIREZ LE MAXIMUM DE VOTRE PROJET D\u2019ISOLATION DE LA MAISON AVEC L\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">En incluant l\u2019\u00e9tanch\u00e9isation compl\u00e8te \u00e0 l\u2019air dans votre projet d\u2019isolation, vous pourrez r\u00e9duire votre consommation d\u2019\u00e9nergie et r\u00e9duire encore plus vos factures \u00e9nerg\u00e9tiques. Une \u00e9tanch\u00e9isation \u00e0 l\u2019air ad\u00e9quate emp\u00eache l\u2019air de circuler \u00e0 travers ou autour de votre isolation. Sans elle, votre isolation peut devenir moins efficace et augmenter votre consommation d\u2019\u00e9nergie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">ZONES FR\u00c9QUENTES D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR<\/h3>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Les techniques d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air varient en fonction de la maison et de la zone \u00e0 isoler. Les zones suivantes sont souvent \u00e9tanch\u00e9is\u00e9es&nbsp;:<\/p>\n\n\n\n<div class=\"wp-block-group is-style-content-wide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<ul class=\"wp-block-list is-style-small\">\n<li class=\"has-medium-font-size\">Dans le grenier&nbsp;: points de p\u00e9n\u00e9tration comme les espaces autour des ventilateurs, des colonnes de plomberie, des luminaires encastr\u00e9s ou autour de la trappe du grenier.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Le long du haut des murs&nbsp;: l\u00e0 o\u00f9 la charpente murale rencontre le plafond, y compris les cloisons int\u00e9rieures.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Autour de la fondation&nbsp;: zones o\u00f9 la fondation rencontre le mur, comme les solives de bordure.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Ouvertures pour l\u2019\u00e9quipement et les services&nbsp;: bouches d\u2019a\u00e9ration, prises d\u2019air, conduits, plomberie et services \u00e9lectriques.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Autour des ouvertures brutes et des joints des fen\u00eatres et des portes.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Lorsque vous \u00e9tanch\u00e9isez votre maison \u00e0 l\u2019air, il est important de r\u00e9gler tout probl\u00e8me d\u2019humidit\u00e9 existant avant de commencer les travaux. En emprisonnant l\u2019humidit\u00e9 dans un endroit bien \u00e9tanch\u00e9is\u00e9, vous pouvez r\u00e9duire le potentiel de s\u00e9chage et aggraver le probl\u00e8me.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Pour en savoir plus, discutez de votre projet avec un fournisseur inscrit d\u2019Efficacit\u00e9 Manitoba ou consultez notre <a href=\"#ressources\">section Ressources<\/a> ci-dessous ou la <a href=\"#foire-aux-questions\">foire aux questions<\/a> ci-dessous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">AVANTAGES DE L\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Vous avez beaucoup \u00e0 gagner en incluant l\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air dans votre projet d\u2019isolation&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-small\">\n<li class=\"has-medium-font-size\">Augmentation de votre efficacit\u00e9 \u00e9nerg\u00e9tique<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Am\u00e9lioration de la qualit\u00e9 de l\u2019air int\u00e9rieur, du confort et de l\u2019insonorisation<\/li>\n\n\n\n<li class=\"has-medium-font-size\">R\u00e9duction du risque de d\u00e9p\u00f4t et d\u2019accumulation d\u2019humidit\u00e9 et de probl\u00e8mes connexes comme la moisissure ou la d\u00e9gradation structurelle.<\/li>\n\n\n\n<li class=\"has-medium-font-size\">Prolongation de la dur\u00e9e de vie de votre syst\u00e8me de chauffage et de ventilation.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">FAITES FRUCTIFIER VOTRE REMISE<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Gr\u00e2ce \u00e0 notre nouvelle prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air, vous pouvez augmenter votre<a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/\" target=\"_blank\" rel=\"noreferrer noopener\"> remise pour l\u2019isolation des maisons<\/a> en fonction de l\u2019ampleur de l\u2019am\u00e9lioration du taux de fuite d\u2019air de votre maison.<\/p>\n\n\n\n<figure class=\"wp-block-flexible-table-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td colspan=\"2\" style=\"background-color:#2493d1;color:#ffffff;font-size:20px;line-height:1.2;text-align:center;border-color:#f2f2f2;padding:10px;border-bottom-width:7px\"><strong>LES PRIMES SONT CALCUL\u00c9ES EN FONCTION DE L\u2019AM\u00c9LIORATION DE L\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR<\/strong><\/td><\/tr><tr><td style=\"background-color:#82c341;color:#ffffff;line-height:1.2;text-align:center;border-color:#f2f2f2;padding:10px;border-right-width:7px\"><strong>% D\u2019AM\u00c9LIORATION<\/strong><\/td><td style=\"background-color:#82c341;color:#ffffff;line-height:1.2;text-align:center;border-color:#f2f2f2;padding:10px;border-left-width:7px\"><strong>MONTANT DE LA PRIME<\/strong><\/td><\/tr><tr><td style=\"line-height:1.2;text-align:center;border-color:#f2f2f2;border-width:7px;padding:10px\">Am\u00e9lioration de 10 %<\/td><td style=\"line-height:1.2;text-align:center;border-color:#f2f2f2;border-width:7px;padding:10px\">500 $<\/td><\/tr><tr><td style=\"line-height:1.2;text-align:center;border-color:#f2f2f2;border-width:7px;padding:10px\">Am\u00e9lioration de 20 %<\/td><td style=\"line-height:1.2;text-align:center;border-color:#f2f2f2;border-width:7px;padding:10px\">750 $<\/td><\/tr><tr><td style=\"line-height:1.2;text-align:center;border-color:#f2f2f2;border-width:7px;padding:10px\">Am\u00e9lioration de 30 %<\/td><td style=\"line-height:1.2;border-style:solid;border-color:#f2f2f2;text-align:center;border-width:7px;padding:10px\">1 000 $<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Pour \u00eatre admissible \u00e0 cette prime, vous devez effectuer une \u00e9valuation \u00c9nerGuide avant et apr\u00e8s les r\u00e9novations afin de quantifier le changement du taux de fuite d\u2019air de votre maison.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Au cours de ces \u00e9valuations, le taux de fuite d\u2019air de votre maison est mesur\u00e9 au moyen d\u2019un essai du moteur souffleur. Les valeurs indiqu\u00e9es dans vos rapports d\u2019\u00e9valuation \u00c9nerGuide sont exprim\u00e9es en unit\u00e9s de taux de renouvellement d\u2019air par heure (tr\/h). Nous d\u00e9terminons l\u2019am\u00e9lioration du taux de fuite d\u2019air de votre maison \u00e0 partir de ces valeurs.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-full slant\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"400\" src=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x.png\" alt=\"\" class=\"wp-image-592\" srcset=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x.png 2000w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-479x96.png 479w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-1024x205.png 1024w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-768x154.png 768w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-1536x307.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#f4f3f3\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-hero-heading\"><strong>MARCHE \u00c0 SUIVRE POUR PARTICIPER<\/strong><\/h2>\n\n\n\n<ol class=\"iconic-list large\">\n<li>\n<h3><strong>OBTENEZ <\/strong>UNE \u00c9VALUATION \u00c9NERGUIDE AVANT LES R\u00c9NOVATIONS<\/h3>\n<p>Pour \u00eatre admissible \u00e0 la prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air, vous devez effectuer votre \u00e9valuation \u00c9nerGuide avant de commencer les travaux dans le cadre de votre projet de remise pour l\u2019isolation des maisons. Communiquez avec un <a href=\"https:\/\/efficiencymb.ca\/fr\/organismes-de-service-energuide\/\" target=\"_blank\" rel=\"noopener\">organisme de services qui offre des \u00e9valuations \u00c9nerGuide pour les maisons existantes<\/a>.\u00a0L\u2019organisme enverra un conseiller en \u00e9nergie pour effectuer une \u00e9valuation du rendement \u00e9nerg\u00e9tique \u00e0 domicile, afin de d\u00e9terminer votre taux actuel de fuite d\u2019air et les zones \u00e0 \u00e9tanch\u00e9iser. Votre conseiller ou conseill\u00e8re en efficacit\u00e9 \u00e9nerg\u00e9tique vous fournira \u00e9galement des conseils d\u2019expert et une feuille de route personnalis\u00e9e des am\u00e9liorations \u00e9co\u00e9nerg\u00e9tiques recommand\u00e9es pour votre maison.<\/p>\n<\/li>\n<li>\n<h3><strong>PLANIFIEZ <\/strong>VOTRE PROJET<\/h3>\n<p>Votre conseiller ou conseill\u00e8re en efficacit\u00e9 \u00e9nerg\u00e9tique vous enverra par courriel vos rapports d\u2019\u00e9valuation avant les r\u00e9novations environ de deux \u00e0 trois semaines apr\u00e8s votre \u00e9valuation. Consultez ces rapports pour conna\u00eetre le taux actuel de fuite d\u2019air de votre maison et les zones de fuite d\u2019air relev\u00e9es par votre conseiller ou conseill\u00e8re en efficacit\u00e9 \u00e9nerg\u00e9tique. Remettez ces rapports \u00e0 votre entrepreneur en isolation pour vous aider \u00e0 planifier l\u2019envergure de votre projet d\u2019isolation et d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.<\/p>\n<\/li>\n<li>\n<h3><strong>DEMANDEZ<\/strong> DES REMISES<\/h3>\n<p><a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-evaluation-energuide-maison\/\" target=\"_blank\" rel=\"noopener\"><strong>Remise pour une \u00e9valuation \u00c9nerGuide de votre maison<\/strong><\/a><\/p>\n<p>Nous offrons une remise de 400\u00a0$ sur le co\u00fbt d\u2019une \u00e9valuation \u00c9nerGuide pr\u00e9alable aux r\u00e9novations. Faites une demande en ligne dans les 90\u00a0jours suivant votre \u00e9valuation \u00c9nerGuide pr\u00e9alable aux r\u00e9novations. Si votre demande est approuv\u00e9e, vous recevrez votre remise dans les quatre \u00e0 six semaines suivant l\u2019envoi de votre demande.<\/p>\n<p><a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/\" target=\"_blank\" rel=\"noopener\"><strong>Remise pour l\u2019isolation des maisons et prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air<\/strong><\/a><\/p>\n<p>Votre entrepreneur ou d\u00e9taillant commencera les proc\u00e9dures d\u2019approbation de votre demande pour vous. Assurez-vous d\u2019obtenir l\u2019approbation avant d\u2019acheter des mat\u00e9riaux ou de commencer des travaux, y compris l\u2019enl\u00e8vement de cloisons s\u00e8ches, de stucco ou de l\u2019isolation originale.<\/p>\n<\/li>\n<li>\n<h3><strong>TERMINEZ<\/strong> VOTRE PROJET ET OBTENEZ UNE \u00c9VALUATION \u00c9NERGUIDE APR\u00c9S LES R\u00c9NOVATIONS<\/h3>\n<p>Une fois votre demande approuv\u00e9e, achetez et installez vos mat\u00e9riaux d\u2019isolation et d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. Vos mat\u00e9riaux doivent \u00eatre achet\u00e9s de l\u2019entrepreneur inscrit ou du d\u00e9taillant autoris\u00e9 dont le nom est indiqu\u00e9 sur votre formulaire de demande. Vous avez 12\u00a0mois pour effectuer l\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air et installer l\u2019isolant \u00e0 partir de la date d\u2019approbation de votre demande.<\/p>\n<p>Une fois les travaux termin\u00e9s, communiquez avec votre conseiller ou conseill\u00e8re en efficacit\u00e9 \u00e9nerg\u00e9tique pour planifier votre \u00e9valuation apr\u00e8s les r\u00e9novations afin de quantifier votre nouveau taux de fuite d\u2019air.\u00a0<\/p>\n<\/li>\n<li>\n<h3><strong>OBTENEZ<\/strong> VOTRE REMISE POUR L&rsquo;ISOLATION DES MAISONS + VOTRE PRIME D&rsquo;\u00c9TANCH\u00c9ISATION \u00c0 L&rsquo;AIR<\/h3>\n<p>Votre fournisseur amorcera le processus d\u2019ach\u00e8vement en envoyant votre facture pay\u00e9e ou vos re\u00e7us. Vous recevrez un formulaire d\u2019ach\u00e8vement par courriel et devrez fournir des copies de vos rapports d\u2019\u00e9valuation \u00c9nerGuide. Nous calculerons votre remise pour l\u2019isolation en fonction de vos valeurs \u00ab R \u00bb v\u00e9rifi\u00e9es, de votre superficie en pieds carr\u00e9s et de vos factures. Votre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air sera bas\u00e9e sur le pourcentage d\u2019am\u00e9lioration du taux de fuite d\u2019air de votre maison. Votre ch\u00e8que de remise sera envoy\u00e9 par la poste \u00e0 l\u2019adresse que vous indiquez dans votre d\u00e9claration d\u2019ach\u00e8vement.<\/p>\n<\/li>\n<\/ol>\n\n\n<div class=\"theme-button wp-block-button aligncenter\">\r\n\t<a target=\"_blank\" class=\"wp-block-button__link has-background no-border-radius button cta button-large\" href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/offre-devaluation-energuide-gratuite\/\"><strong>EN SAVIOUR PLUS SUR NOTRE REMISE<\/strong><br>\u00c9NERGUIDE POUR UNE \u00c9VALUATION \u00c9NERGUIDE \u00c0 DOMICILE<\/a>\r\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"400\" src=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1.png\" alt=\"\" class=\"wp-image-12078\" srcset=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1.png 2000w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1-479x96.png 479w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1-1024x205.png 1024w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1-768x154.png 768w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-two-tone-green@2x-edited-1-1536x307.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n<\/div>\n\n\n<a name=\"do-you-qualify\"><\/a>\n\n\n\n<div class=\"wp-block-group is-style-content-columns\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-hero-heading\" id=\"etes-vous-admissible?\">\u00caTES-VOUS ADMISSIBLE?<\/h2>\n\n\n\n<ul class=\"wp-block-list is-style-medium has-medium-font-size\">\n<li>Vous \u00eates propri\u00e9taire de la r\u00e9sidence (maison, immeuble locatif ou chalet).<\/li>\n\n\n\n<li>La r\u00e9sidence b\u00e9n\u00e9ficie d\u2019un service r\u00e9sidentiel actif de Manitoba Hydro et est chauff\u00e9e pendant toute la saison de chauffage (de septembre \u00e0 mai).<\/li>\n\n\n\n<li>Votre domicile n\u2019a jamais b\u00e9n\u00e9fici\u00e9 d\u2019une remise pour la zone vis\u00e9e par votre demande.<\/li>\n\n\n\n<li>Il s\u2019agit d\u2019une maison isol\u00e9e, jumel\u00e9e ou mobile\/modulaire sur une fondation permanente raccord\u00e9e en permanence au r\u00e9seau d\u2019approvisionnement en eau.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-content-columns\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-hero-heading\">PROJETS INADMISSIBLES<\/h2>\n\n\n\n<ul class=\"wp-block-list is-style-medium--x has-medium-font-size\">\n<li>Projets en cours, d\u00e9j\u00e0 termin\u00e9s ou convertissant des espaces non chauff\u00e9s en espaces chauff\u00e9s<\/li>\n\n\n\n<li>Garages, solariums, porches ou v\u00e9randas trois saisons<\/li>\n\n\n\n<li>Maisons saisonni\u00e8res, locations de vacances, maisons inoccup\u00e9es ou d\u00e9pendances<\/li>\n\n\n\n<li>Nouvelles constructions (maisons neuves ou rajouts)<\/li>\n\n\n\n<li>Plinthes ou isolation des planchers pour maison mobile<\/li>\n<\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-content-wide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"ressources\">RESSOURCES<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Vous voulez en savoir plus? Consultez ces ressources pour en savoir plus sur l\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hydro.mb.ca\/docs\/resources\/1_sealing_caulking_and_weatherstripping.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sealing, caulking and weatherstripping (\u00e9tanch\u00e9isation, calfeutrage et coupe-froid)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/ressources-naturelles.canada.ca\/efficacite-energetique\/efficacite-energetique-maison\/emprisonnons-chaleur-section-4-mettre-fin-fuites-air-dans-votre-maison\" target=\"_blank\" rel=\"noreferrer noopener\">Mettre fin aux fuites d\u2019air dans votre maison<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.bchousing.org\/publications\/best-practices-air-sealing-insulation-retrofits.pdf\"><\/a><a href=\"https:\/\/www.bchousing.org\/publications\/best-practices-air-sealing-insulation-retrofits.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Best practice guide for air sealing and insulation retrofits (guide des meilleures pratiques pour les r\u00e9novations d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air et d\u2019isolation)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/efficiencymb.ca\/fr\/articles\/air-sealing-101\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9tanch\u00e9isation&nbsp;101<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" id=\"foire-aux-questions\">Consultez notre&nbsp;<a href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-etancheisation-air-foire-aux-questions\/\" target=\"_blank\" rel=\"noreferrer noopener\">foire aux questions<\/a>&nbsp;pour en savoir plus.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"400\" src=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x.png\" alt=\"\" class=\"wp-image-612\" srcset=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x.png 2000w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x-479x96.png 479w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x-1024x205.png 1024w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x-768x154.png 768w, https:\/\/efficiencymb.ca\/wp-content\/uploads\/bg-bottom-only-blue-green@2x-1536x307.png 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Am\u00e9liorez encore plus votre isolation gr\u00e2ce \u00e0 l\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air. En r\u00e9duisant les fuites d\u2019air, vous pouvez am\u00e9liorer le rendement \u00e9nerg\u00e9tique de votre maison et \u00eatre admissible \u00e0 des \u00e9conomies suppl\u00e9mentaires.<\/p>\n","protected":false},"author":10,"featured_media":21187,"parent":13124,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-89896","page","type-page","status-publish","has-post-thumbnail","hentry","page_cat-programs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba<\/title>\n<meta name=\"description\" content=\"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba\" \/>\n<meta property=\"og:description\" content=\"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/\" \/>\n<meta property=\"og:site_name\" content=\"Efficiency Manitoba\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T20:19:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/efficiencymb.ca\/wp-content\/uploads\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/\",\"name\":\"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg\",\"datePublished\":\"2026-08-05T13:00:00+00:00\",\"dateModified\":\"2026-08-25T20:19:20+00:00\",\"description\":\"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg\",\"width\":2250,\"height\":1266,\"caption\":\"Man installing fiberglass insulation in the wall.Please also see:\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/prime-detancheisation-a-lair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ma Maison\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remise pour l\u2019isolation des maisons\",\"item\":\"https:\\\/\\\/efficiencymb.ca\\\/fr\\\/ma-maison\\\/remise-pour-lisolation-des-maisons\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#website\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"name\":\"Efficiency Manitoba\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/efficiencymb.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#organization\",\"name\":\"Efficiency Manitoba\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"contentUrl\":\"https:\\\/\\\/efficiencymb.ca\\\/wp-content\\\/uploads\\\/em-logo-white-en.png\",\"width\":388,\"height\":91,\"caption\":\"Efficiency Manitoba\"},\"image\":{\"@id\":\"https:\\\/\\\/efficiencymb.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.\",\"legalName\":\"Efficiency Manitoba\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba","description":"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/","og_locale":"fr_FR","og_type":"article","og_title":"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba","og_description":"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.","og_url":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/","og_site_name":"Efficiency Manitoba","article_modified_time":"2026-08-25T20:19:20+00:00","og_image":[{"width":2250,"height":1266,"url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/","url":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/","name":"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR &#8212; Efficiency Manitoba","isPartOf":{"@id":"https:\/\/efficiencymb.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#primaryimage"},"image":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#primaryimage"},"thumbnailUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg","datePublished":"2026-08-05T13:00:00+00:00","dateModified":"2026-08-25T20:19:20+00:00","description":"Am\u00e9liorez l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique de votre maison, r\u00e9duisez les fuites d\u2019air et faites fructifier votre remise sur votre projet d\u2019isolation gr\u00e2ce \u00e0 notre prime d\u2019\u00e9tanch\u00e9isation \u00e0 l\u2019air.","breadcrumb":{"@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#primaryimage","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/Gentleman-installing-insulation-1-scaled-e1689967502112.jpg","width":2250,"height":1266,"caption":"Man installing fiberglass insulation in the wall.Please also see:"},{"@type":"BreadcrumbList","@id":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/prime-detancheisation-a-lair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/efficiencymb.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Ma Maison","item":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/"},{"@type":"ListItem","position":3,"name":"Remise pour l\u2019isolation des maisons","item":"https:\/\/efficiencymb.ca\/fr\/ma-maison\/remise-pour-lisolation-des-maisons\/"},{"@type":"ListItem","position":4,"name":"PRIME D\u2019\u00c9TANCH\u00c9ISATION \u00c0 L\u2019AIR"}]},{"@type":"WebSite","@id":"https:\/\/efficiencymb.ca\/#website","url":"https:\/\/efficiencymb.ca\/","name":"Efficiency Manitoba","description":"","publisher":{"@id":"https:\/\/efficiencymb.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efficiencymb.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/efficiencymb.ca\/#organization","name":"Efficiency Manitoba","url":"https:\/\/efficiencymb.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/","url":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","contentUrl":"https:\/\/efficiencymb.ca\/wp-content\/uploads\/em-logo-white-en.png","width":388,"height":91,"caption":"Efficiency Manitoba"},"image":{"@id":"https:\/\/efficiencymb.ca\/#\/schema\/logo\/image\/"},"description":"Manitoba's Crown corporation dedicated to energy efficiency and long-term energy savings.","legalName":"Efficiency Manitoba"}]}},"_links":{"self":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/89896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/comments?post=89896"}],"version-history":[{"count":8,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/89896\/revisions"}],"predecessor-version":[{"id":91777,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/89896\/revisions\/91777"}],"up":[{"embeddable":true,"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/pages\/13124"}],"wp:attachment":[{"href":"https:\/\/efficiencymb.ca\/fr\/wp-json\/wp\/v2\/media?parent=89896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}